{"id":35804,"date":"2019-03-03T21:06:42","date_gmt":"2019-03-03T20:06:42","guid":{"rendered":"https:\/\/www.hcb.net\/?p=35804"},"modified":"2019-03-03T22:47:57","modified_gmt":"2019-03-03T21:47:57","slug":"dezimierte-bozner-verlieren-heimspiel-gegen-red-bull-salzburg-knapp-mit-43","status":"publish","type":"post","link":"https:\/\/www.hcb.net\/de\/dezimierte-bozner-verlieren-heimspiel-gegen-red-bull-salzburg-knapp-mit-43\/","title":{"rendered":"Dezimierte Bozner verlieren Heimspiel gegen Red Bull Salzburg knapp mit 4:3"},"content":{"rendered":"<p>Der HCB S\u00fcdtirol Alperia musste im heutigen Match gegen Red Bull Salzburg mit einem stark dezimierten Team auftreten. Durch Verletzungen fehlten die zwei Standardverteidiger MacKenzie und Geiger: als Ersatz wurde zum zweiten Mal der Rittner Ivan Tauferer ins wei\u00dfrote Trikot einberufen, w\u00e4hrend Marco Insam vom Sturm in die Defensive wechselte. Im Angriff musste auch der angeschlagene Brett Findlay passen, sodass Coach Kai Suikkanen gezwungen war, bis auf die Linie mit Bernard-Frigo-Miceli alle Sturmformationen neu aufzustellen. Sicher keine leichte Aufgabe f\u00fcr die Foxes gegen den Dauerrivalen aus Salzburg, denn dieses Spiel k\u00f6nnte voraussichtlich eine Vorentscheidung um den vierten Tabellenplatz der Pick Round bzw. das Heimrecht f\u00fcr die Playoff bringen. Nach einem starken Startdrittel der Foxes kippten die G\u00e4ste im mittleren Abschnitt durch ein Black Out der Wei\u00dfroten das Ergebnis zu ihren Gunsten, legten im Schlussabschnitt noch ein Tor nach und konnten die verzweifelte Schlussoffensive der Hausherren mit M\u00fche gerade noch abwehren.<\/p>\n<p>Hervorragendes erstes Drittel der Foxes durch zwei sch\u00f6n herausgespielte Tore von Nordlund und Brace. Eigentlich h\u00e4tten die Wei\u00dfroten drei Tore erzielt, doch durch eine krasse Fehlentscheidung der Unparteiischen wurde dieses nicht anerkannt. Was war geschehen?\u00a0 Der Salzburger Goalie Michalek konnte die Scheibe auf Schuss von Marchetti nicht festhalten, diese blieb frei vor dem Tor liegen und Brace gab dieser den Gnadensto\u00df, doch die Referees hatten bereits unverst\u00e4ndlicherweise abgepfiffen! Das Match kam zu Beginn etwas langsam in die G\u00e4nge, auf Salzburger Seite pr\u00fcfte Trattnig den Bozner Torh\u00fcter mit einem Distanzschuss, auf Bozner Seite war es Campbell von der blauen Linie. In der elften Minute ereignete sich dann die oben beschriebene Aktion, drei Minuten sp\u00e4ter startete Nordlund aus dem eigenen Drittel, sein Zuspiel wurde zwar abgefangen, die Scheibe kam wieder zu ihm zur\u00fcck und diesmal versenkte er diese im gegnerischen Kasten. Bei der ersten \u00dcberzahl des Spieles kurz danach schlugen die Foxes erneut zu: eine perfekte Powerplay Stafette \u00fcber Petan und Miceli schloss Brace (MVP des Matches) aus k\u00fcrzester Distanz ab.<\/p>\n<p>Salzburg erwischte einen Traumstart in den mittleren Abschnitt, denn nach 18 Sekunden erzielte Duncan im Konter auf Rebound nach einem Schuss von Hughes den Anschlusstreffer. Bozen versuchte sofort zu reagieren: zuerst verwehrte Michalek Blunden den dritten Bozner Treffer, dann rettete der Salzburger Goalie auf Frigo, der von Miceli freigespielt wurde. Zur H\u00e4lfte des Drittels entwischte Catenacci im Konter, spielte Frank an und wieder blieb Michalek Sieger. Schrecksekunde bei einem Powerplay f\u00fcr Bozen, als Harris in Unterzahl allein auf den Bozner Kasten zulief, Irving stoppte den Versuch mit einem Big Save. Die vierzehnte Minute war dann f\u00fcr die Hausherren fatal und stellte das Ergebnis auf den Kopf: zuerst veredelte Trattnig mit einem Onetimer ein Zuspiel von Cijan, dann leitete ein Fehler der Bozner Defensive das Tor von Hughes ein.<\/p>\n<p>Gazley er\u00f6ffnete den Schlussabschnitt mit einem Distanzschuss, Irving gew\u00e4hrte den Rebound und zog Herburger beim Nachschuss den Zahn. Die Foxes \u00fcberstanden zwei Powerplay der G\u00e4ste ohne Konsequenzen, kassierten aber sofort nach der R\u00fcckkehr auf das Eis von Bernard den spielentscheidenden vierten Treffer durch Gazley, der nach einer Abwehr mit letztem Einsatz von Marchetti abstaubte. Die verzweifelte Schlussoffensive der Foxes brachte den Anschlusstreffer von Brace knapp zwei Minuten vor Spielende, der Ausgleich, den Deluca in allerletzter Sekunde auf dem Schl\u00e4ger hatte, wollte aber nicht mehr gelingen.<\/p>\n<p>Der HCB S\u00fcdtirol Alperia ist durch diese ungl\u00fcckliche Heimniederlage gegen den direkten Gegner auf den f\u00fcnften Tabellenrang abgerutscht und hat nun noch drei Spieltage zur Verf\u00fcgung, doch noch den ersehnten vierten Platz zu erobern. N\u00e4chster Termin f\u00fcr Bernard &amp; Co. ist am Dienstag, 5. M\u00e4rz mit dem Ausw\u00e4rtsspiel in Fehervar (18,00 Uhr).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>HCB S\u00fcdtirol Alperia \u2013 EC Red Bull Salzburg 3:4 <\/strong>(2:0 \u2013 0:3 \u2013 1:1)<\/p>\n<p><strong>Die Tore:<\/strong> 14:37 Markus Nordlund (1:0) \u2013 17:25 PP1 Riley Brace (2:0) \u2013 20:18 Ryan Duncan (2:1) &#8211; 34:08 Matthias Trattnig (2:2) \u2013 35:06 John Hughes (2:3) \u2013 51:35 Dustin Gazley (2:4) \u2013 58:12 Riley Brace (3:4)<\/p>\n<p><strong>Schiedsrichter<\/strong>: Piragic\/Trilar \u2013 Pardatscher\/Sparer<\/p>\n<p><strong>Zuschauer:<\/strong> 2790<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Tabelle Pick Round nach 7 Spieltagen<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"25\">1.<\/td>\n<td width=\"136\">Vienna Capitals<\/td>\n<td width=\"58\">24 Punkte<\/td>\n<\/tr>\n<tr>\n<td width=\"25\">2.<\/td>\n<td width=\"136\">Graz99ers<\/td>\n<td width=\"58\">19<\/td>\n<\/tr>\n<tr>\n<td width=\"25\">3.<\/td>\n<td width=\"136\">EC KAC<\/td>\n<td width=\"58\">13<\/td>\n<\/tr>\n<tr>\n<td width=\"25\">4<strong>.<\/strong><\/td>\n<td width=\"136\">Red Bull Salzburg<\/td>\n<td width=\"58\">10<\/td>\n<\/tr>\n<tr>\n<td width=\"25\"><strong>5.<\/strong><\/td>\n<td width=\"136\"><strong>HC Bozen<\/strong><\/td>\n<td width=\"58\"><strong>7<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"25\">6.<\/td>\n<td width=\"136\">Fehervar AV19<\/td>\n<td width=\"58\">3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Der HCB S\u00fcdtirol Alperia musste im heutigen Match gegen Red Bull Salzburg mit einem stark dezimierten Team auftreten. Durch Verletzungen fehlten die zwei Standardverteidiger MacKenzie und Geiger: als Ersatz wurde zum zweiten Mal der Rittner Ivan Tauferer ins wei\u00dfrote Trikot einberufen, w\u00e4hrend Marco Insam vom Sturm in die Defensive wechselte. Im Angriff musste auch der [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":35802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-35804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-team"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/posts\/35804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/comments?post=35804"}],"version-history":[{"count":6,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/posts\/35804\/revisions"}],"predecessor-version":[{"id":35811,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/posts\/35804\/revisions\/35811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/media\/35802"}],"wp:attachment":[{"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/media?parent=35804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/categories?post=35804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hcb.net\/de\/wp-json\/wp\/v2\/tags?post=35804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}