{"id":36242,"date":"2019-03-13T22:57:55","date_gmt":"2019-03-13T21:57:55","guid":{"rendered":"https:\/\/www.hcb.net\/?p=36242"},"modified":"2019-03-13T22:57:55","modified_gmt":"2019-03-13T21:57:55","slug":"gara-1-e-del-klagenfurt-kozek-decide-allovertime-un-match-spettacolare","status":"publish","type":"post","link":"https:\/\/www.hcb.net\/it\/gara-1-e-del-klagenfurt-kozek-decide-allovertime-un-match-spettacolare\/","title":{"rendered":"Gara 1 \u00e8 del Klagenfurt \u2013 Kozek decide all\u2019overtime un match spettacolare"},"content":{"rendered":"<p>La prima battaglia \u00e8 dell\u2019EC KAC. Gli austriaci si aggiudicano una spettacolare gara 1, battendo l\u2019HCB Alto Adige Alperia per 5 a 4 grazie al goal di Kozek dopo soli 41 secondi dell\u2019overtime. Prima un botta e risposta durato 60 minuti, con i Foxes tre volte in vantaggio e tre volte rimontati, ma anche capaci di pareggiare i conti dopo il provvisorio 4 a 3 dei padroni di casa. In grande spolvero capitan Anton Bernard, autore di una straordinaria doppietta che purtroppo non \u00e8 bastata per portare a casa il primo incontro della serie.<\/p>\n<p>La cronaca. Per il loro esordio sulla panca del Bolzano, coach Clayton Beddoes e l\u2019assistant coach Alexander Egger rinunciano agli infortunati Findlay, Crescenzi, MacKenzie e Irving. Rientrano Geiger, Insam e Catenacci, tra i pali c\u2019\u00e8 Jake Smith.<\/p>\n<p>Il Klagenfurt si rende subito pericoloso con un paio di tiri dalla distanza, ma la prima grossa occasione del match la creano i biancorossi, con Miceli che serve a rimorchio Nordlund, che spara per\u00f2 clamorosamente fuori. Al 07:05 ecco il vantaggio del Bolzano: Miceli serve Bernard davanti alla porta, si scatena una mischia risolta proprio dal capitano, che supera Madlener. Pochi minuti dopo il KAC risponde: conclusione di Petersen, rebound concesso da Smith e tocco vincente di Andrew Kozek. I Foxes non mollano e colpiscono l\u2019esterno del palo con Carozza, poi Smith abbassa la saracinesca con il Klagenfurt in powerplay: fondamentali le sue parate su Kozek e Neal. 1 a 1 dopo 20 minuti.<\/p>\n<p>I biancorossi possono giostrare in powerplay in avvio di periodo centrale e colpiscono ancora: Petan consegna il disco a Nordlund, che con un siluro batte Madlener e sigla il 2 a 1. Passano appena 58 secondi, per\u00f2, e il KAC pareggia nuovamente, con un missile questa volta di Unterweger. I padroni di casa aumentano il ritmo, il Bolzano tiene e quando si ritrova nuovamente con l\u2019uomo in pi\u00f9 torna a condurre: ancora Nordlund protagonista, questa volta con un tiro deviato da Blunden. Il Klagenfurt per\u00f2 non desiste e, sostenuto dal proprio pubblico, lancia l\u2019assedio: Smith si oppone su Liivik, poi in powerplay Kozek colpisce prima una traversa e poi un palo, infine per\u00f2 al 36:26 Bischofberger riesce a infilarsi tra le maglie della retroguardia biancorossa e tutto solo davanti a Smith non sbaglia. 3 a 3 e grande spettacolo alla seconda sirena.<\/p>\n<p>Klagenfurt subito in powerplay nei primi minuti nel terzo drittel e Thomas Koch, con un tiro al volo sull\u2019assist di Petersen, porta per la prima volta in vantaggio i suoi. Il Bolzano non ci sta, sfiora il pareggio con Petan e poi lo ottiene, al 47:14, con una meraviglia di Anton Bernard, che da posizione defilata piazza il disco all\u2019incrocio dei pali. I ritmi sono altissimi, si lotta su ogni disco e le squadre non si risparmiano. Nel finale brividi per i Foxes: prima Smith mette una pezza su un disco vagante davanti alla porta, poi si appella alla dea bendata quando Petersen semina il panico nella retroguardia biancorossa e Kozek colpisce il palo a porta praticamente sguarnita.<\/p>\n<p>Si va all\u2019overtime e al Klagenfurt bastano appena 41 secondi: Kozek riceve il disco da Petersen, prende la mira e batte Smith sul palo lontano. Gara 1 \u00e8 del KAC, l\u2019appuntamento \u00e8 al Palaonda, venerd\u00ec 15 marzo alle 19:15, per gara 2. La prevendita continua online e al Palaonda (gioved\u00ec dalle 15 alle 18 e venerd\u00ec dalle 11 alle 14, con le casse serali che apriranno alle 17).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>EC KAC \u2013 HCB Alto Adige Alperia 5 \u2013 4 [1-1; 2-2; 1-1; 1-0] \u2013 Serie: 1 \u2013 0 <\/strong><\/p>\n<p><strong>Reti: <\/strong>07:05 Anton Bernard (0-1); 12:52 Andrew Kozek (1-1); 21:39 Markus Nordlund PP1 (1-2); 22:37 Clemens Unterweger (2-2); 28:10 Mike Blunden PP1 (2-3); 36:26 Johannes Bischofberger (3-3); 42:46 Thomas Koch PP1 (4-3); 47:14 Anton Bernard (4-4); 60:41 Andrew Kozek (5-4)<\/p>\n<p><strong>Arbitri: <\/strong>Garon, Zrnic \/ Kontschieder, Nothegger<br \/>\n<strong>Spettatori: <\/strong>3.192<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prima battaglia \u00e8 dell\u2019EC KAC. Gli austriaci si aggiudicano una spettacolare gara 1, battendo l\u2019HCB Alto Adige Alperia per 5 a 4 grazie al goal di Kozek dopo soli 41 secondi dell\u2019overtime. Prima un botta e risposta durato 60 minuti, con i Foxes tre volte in vantaggio e tre volte rimontati, ma anche capaci [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":36243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-36242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-team-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts\/36242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/comments?post=36242"}],"version-history":[{"count":1,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts\/36242\/revisions"}],"predecessor-version":[{"id":36245,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts\/36242\/revisions\/36245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/media\/36243"}],"wp:attachment":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/media?parent=36242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/categories?post=36242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/tags?post=36242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}