{"id":60782,"date":"2022-10-13T10:14:05","date_gmt":"2022-10-13T09:14:05","guid":{"rendered":"https:\/\/www.hcb.net\/?p=60782"},"modified":"2022-10-13T10:19:08","modified_gmt":"2022-10-13T09:19:08","slug":"il-bolzano-vuole-difendere-il-primo-posto-venerdi-il-graz-in-casa-domenica-a-lubiana-in-diretta-su-vb33","status":"publish","type":"post","link":"https:\/\/www.hcb.net\/it\/il-bolzano-vuole-difendere-il-primo-posto-venerdi-il-graz-in-casa-domenica-a-lubiana-in-diretta-su-vb33\/","title":{"rendered":"Il Bolzano vuole difendere il primo posto \u2013 Venerd\u00ec il Graz in casa, domenica a Lubiana in diretta su VB33"},"content":{"rendered":"<p>Dopo un weekend da 6 punti da incorniciare, con le vittorie esterne a Salisburgo e Brunico, l\u2019HCB Alto Adige Alperia affila le lame per affrontare il suo primo weekend da capolista.<\/p>\n<p><strong>Prima sfida stagionale contro il Graz<\/strong><br \/>\nDomenica 14 ottobre, alle ore 19:45, alla Sparkasse Arena di Bolzano arriveranno i <strong>Graz99ers<\/strong>. Protagonisti di un avvio in sordina, gli stiriani stanno cercando di risalire la china. Dopo quattro KO nelle prime cinque uscite, infatti, sono arrivate due vittorie esterne consecutive, prima a Villach, poi all\u2019overtime in quel di Fehervar. Con 13 goal segnati quello dei 99ers \u00e8 in questo momento il peggior attacco del campionato, in coabitazione con Vienna e Val Pusteria. Attenzione per\u00f2, perch\u00e9 il pacchetto avanzato ha tutte le carte in regola per dare fuoco alle polveri e quello arretrato lavora gi\u00e0 bene: 17 goal subiti, numeri che valgono la quarta miglior difesa della lega.<\/p>\n<p>In casa HCB invece le reti non mancano: 27 quelle messe a segno nelle prime sette giornate, il secondo miglior attacco subito dopo quello dell\u2019Innsbruck. Ma a fare la differenza c\u2019\u00e8 anche la difesa, la migliore della ICE con soli 12 goal incassati: un grosso spicchio di merito va ai due goalies, Sam Harvey e Andreas Bernard, che parano entrambi con una media del 93,9%.<\/p>\n<p><strong>I precedenti tra Bolzano e Graz<br \/>\n<\/strong>Negli ultimi 9 anni Foxes e 99ers hanno incrociato le stecche 44 volte, con rispettivamente 25 vittorie a 19. Il match sar\u00e0 trasmesso in diretta streaming pay-per-view su <a href=\"https:\/\/live.ice.hockey\">https:\/\/live.ice.hockey<\/a>.<\/p>\n<p><strong>Domenica la trasferta in Slovenia<br \/>\n<\/strong>Domenica 16 ottobre, alle ore 17:30, Frank e compagni saranno di scena alla Hala Tivoli di Lubiana, tana dell\u2019<strong>HK SZ Olimpija<\/strong>. <strong>Il match sar\u00e0 trasmesso in diretta su VB33<\/strong>, con la telecronaca di Luca Tommasini e Fabio Larcher.<\/p>\n<p>Gli sloveni sono approdati in ICE Hockey League l\u2019anno scorso, dopo aver vinto per due volte la Alps Hockey League in quattro anni di partecipazione. La prima annata si \u00e8 rivelata positiva, con una squadra che si \u00e8 a lungo mantenuta nei primi posti in classifica e con l\u2019approdo ai playoffs, terminati con l\u2019eliminazione ai quarti contro il VSV. Sulle quattro partite che avrebbero messo a confronto i Foxes con l\u2019Olimpija, due sono state cancellate per via del Covid: nelle altre due, gli sloveni hanno avuto la meglio. C\u2019\u00e8 per\u00f2 gi\u00e0 un precedente in questa stagione: il 18 settembre scorso, alla Sparkasse Arena, il Bolzano si \u00e8 imposto per 4 a 1 grazie alle reti di Halmo, Frank, Mitch Hults e Dalhuisen. L\u2019Olimpija da questo weekend in poi potr\u00e0 concentrarsi esclusivamente sul campionato: ieri, infatti, ha concluso la sua esperienza in CHL (sei sconfitte su sei partite nel girone di ferro con Zug, Turku e Wolfsburg), alla quale ha avuto modo di partecipare grazie a una wild card.<\/p>\n<p>\u201cDobbiamo scendere sul ghiaccio concentrati \u2013 spiega l\u2019attaccante biancorosso Mike Halmo, protagonista di una partenza fulminante con 6 goal e 2 assist \u2013, le cose stanno andando bene, ma non possiamo permetterci cali di concentrazione: a Feldkirch, quasi due settimane fa, abbiamo imparato una lezione e sappiamo che dobbiamo giocare come sappiamo per 60 minuti\u201d.<\/p>\n<p><strong>Il roster del Bolzano<br \/>\n<\/strong>Coach Glen Hanlon schierer\u00e0 sul ghiaccio con tutta probabilit\u00e0 lo stesso lineup visto il weekend scorso. Diego Gl\u00fcck \u00e8 tornato oggi ad allenarsi sul ghiaccio e potrebbe essere pronto al rientro la prossima settimana. Anche Matt Frattin, ancora in ripresa dall\u2019infortunio rimediato a Feldkirch, sar\u00e0 fuori dai giochi per il weekend e potrebbe rientrare in una delle partite del fine settimana successivo.<\/p>\n<p><strong>I biglietti<br \/>\n<\/strong>I biglietti per la partita di venerd\u00ec sono in vendita online su <a href=\"https:\/\/www.midaticket.it\/eventi\/hockey-club-bolzano\">https:\/\/www.midaticket.it\/eventi\/hockey-club-bolzano<\/a> , mentre le casse il giorno della partita apriranno dalle 12:30 alle 14:30 e da alle ore 17:45 in poi.<\/p>\n<p>Alla Sparkasse Arena \u00e8 stato inoltre aperto un nuovo \u201csettore famiglie\u201d, che prevede pacchetti giornalieri a prezzi vantaggiosi: <a href=\"https:\/\/www.hcb.net\/it\/alla-sparkasse-arena-apre-il-settore-famiglia-prezzi-vantaggiosi-nel-settore-b\/\">https:\/\/www.hcb.net\/it\/alla-sparkasse-arena-apre-il-settore-famiglia-prezzi-vantaggiosi-nel-settore-b\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Venerd\u00ec 14 ottobre, ore 19:45 \u2013 Sparkasse Arena, Bolzano \u2013 PPV-Livestream on <a href=\"https:\/\/live.ice.hockey\">https:\/\/live.ice.hockey<\/a><br \/>\n<strong>HCB Alto Adige Alperia vs Graz99ers<\/strong><\/p>\n<p>Domenica 16 ottobre, ore 17:30 \u2013 Hala Tivoli, Lubiana \u2013 Diretta tv su VB33<br \/>\n<strong>HK SZ Olimpija vs HCB Alto Adige Alperia <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>La classifica<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"33\"><strong>\u00a0<\/strong><\/td>\n<td width=\"193\"><strong>Team<\/strong><\/td>\n<td width=\"32\"><strong>GP<\/strong><\/td>\n<td width=\"36\"><strong>PTS<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"33\"><strong>1.<\/strong><\/td>\n<td width=\"193\"><strong>HCB Alto Adige Alperia<\/strong><\/td>\n<td width=\"32\"><strong>7<\/strong><\/td>\n<td width=\"36\"><strong>18<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"33\">2.<\/td>\n<td width=\"193\">Steinbach Black Wings Linz<\/td>\n<td width=\"32\">8<\/td>\n<td width=\"36\">17<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">3.<\/td>\n<td width=\"193\">HC TIWAG Innsbruck<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">15<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">4.<\/td>\n<td width=\"193\">EC Red Bull Salzburg<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">15<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">5.<\/td>\n<td width=\"193\">EC KAC<\/td>\n<td width=\"32\">8<\/td>\n<td width=\"36\">14<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">6.<\/td>\n<td width=\"193\">Hydro Fehervar AV19<\/td>\n<td width=\"32\">8<\/td>\n<td width=\"36\">11<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">7.<\/td>\n<td width=\"193\">HK SZ Olimpija<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">11<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">8.<\/td>\n<td width=\"193\">EC iDM W\u00e4rmepumpen VSV<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">9<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">9.<\/td>\n<td width=\"193\">spusu Vienna Capitals<\/td>\n<td width=\"32\">6<\/td>\n<td width=\"36\">9<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">10.<\/td>\n<td width=\"193\">Moser Medical Graz99ers<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">9<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">11.<\/td>\n<td width=\"193\">Bemer Pioneers Vorarlberg<\/td>\n<td width=\"32\">8<\/td>\n<td width=\"36\">7<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">12.<\/td>\n<td width=\"193\">HC Val Pusteria<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">3<\/td>\n<\/tr>\n<tr>\n<td width=\"33\">13.<\/td>\n<td width=\"193\">Migross Supermercati Asiago<\/td>\n<td width=\"32\">7<\/td>\n<td width=\"36\">3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Kasslatter: &quot;Wir kommen von einer guten Serie und wir werden versuchen, so weiterzumachen&quot;\" width=\"1210\" height=\"681\" src=\"https:\/\/www.youtube.com\/embed\/SDteUgr2Xv4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo un weekend da 6 punti da incorniciare, con le vittorie esterne a Salisburgo e Brunico, l\u2019HCB Alto Adige Alperia affila le lame per affrontare il suo primo weekend da capolista. Prima sfida stagionale contro il Graz Domenica 14 ottobre, alle ore 19:45, alla Sparkasse Arena di Bolzano arriveranno i Graz99ers. Protagonisti di un avvio [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":60783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-60782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-team-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts\/60782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/comments?post=60782"}],"version-history":[{"count":1,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts\/60782\/revisions"}],"predecessor-version":[{"id":60785,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/posts\/60782\/revisions\/60785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/media\/60783"}],"wp:attachment":[{"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/media?parent=60782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/categories?post=60782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hcb.net\/it\/wp-json\/wp\/v2\/tags?post=60782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}